{"id":5825,"date":"2017-10-23T09:58:16","date_gmt":"2017-10-23T06:58:16","guid":{"rendered":"http:\/\/bioretina.net\/2022\/erkrankungen-des-sehnervs-sehnerv-und-der-sehwege-optik-neuropathie\/"},"modified":"2022-06-14T09:02:54","modified_gmt":"2022-06-14T06:02:54","slug":"erkrankungen-des-sehnervs-sehnerv-und-der-sehwege-optik-neuropathie","status":"publish","type":"post","link":"https:\/\/bioretina.net\/de\/erkrankungen-des-sehnervs-sehnerv-und-der-sehwege-optik-neuropathie\/","title":{"rendered":"Erkrankungen Des Sehnervs (Sehnerv) Und Der Sehwege (Optik-Neuropathie)"},"content":{"rendered":"<div id=\"pl-5825\"  class=\"panel-layout\" ><div id=\"pg-5825-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-5825-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-5825-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong><a href=\"https:\/\/www.youtube.com\/watch?v=RM12VAcFVuA\">PRP GROWTH FACTOR INJECTIONS<\/a><br \/>\n<a href=\"http:\/\/magnovision.net\/\">MAGNOVISION THERAPY<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=dQHPyfV4go4&amp;feature=youtu.be\">PHOTOBIOMODULATION THERAPY<\/a><\/strong><\/p>\n<p>Die Sehfunktion beginnt, wenn Strahlen von Objekten auf der Netzhaut fokussiert werden. Lichtenergie wird in der Netzhaut in elektrische Energie umgewandelt. Diese elektrischen Impulse werden zum Sehzentrum im Gehirn \u00fcbertragen, indem sie durch den Sehnerv, das Sehchiasma und den Sehtrakt, die als Sehbahnen bezeichnet werden, geleitet werden. Aus der Netzhaut austretende Nervenfasern verschmelzen zum Sehnerv.<\/p>\n<p>Der Sehnerv kann aus verschiedenen Gr\u00fcnden gesch\u00e4digt werden und es kann zu Seh- oder Gesichtsfeldverlusten kommen.<\/p>\n<p>Ursachen einer Erkrankung des Sehnervs:<\/p>\n<p>Kompression des Sehnervs: aufgrund von Erkrankungen der Schilddr\u00fcse (Kropf).<\/p>\n<p>Infektion des Sehnervs: am h\u00e4ufigsten aufgrund einer Mittelohrentz\u00fcndung und Sinusitis<\/p>\n<p>Isch\u00e4mie des Sehnervs, d.h. Verschluss der Gef\u00e4\u00dfe, die den Sehnerv versorgen<\/p>\n<p>nicht arteritisch (Diabetes, Bluthochdruck ist die h\u00e4ufigste Ursache)<\/p>\n<p>arteritisch (aufgrund einer arteriellen Entz\u00fcndung: Dies ist ein sehr schwerer Zustand,<\/p>\n<p>Es kann zur Erblindung beider Augen kommen, wenn die Behandlung nicht sofort begonnen wird.<\/p>\n<p>Traumatischer Schnitt oder Verletzung des Sehnervs<\/p>\n<p>Sch\u00e4digung der Sehnervenscheide bei Krankheiten, die mit einem Verlust der Nervenscheide fortschreiten und Multiple Sklerose genannt werden.<\/p>\n<p>Toxische Wirkungen auf den Sehnerv durch Alkohol (Methylalkohol), Tuberkulose-Medikamente wie Ethambutol-Isoniazid, Sch\u00e4den durch Strahlentherapie<\/p>\n<p>Sch\u00e4digung des Sehnervs als Folge einiger systemischer Erkrankungen wie Lupus-Beh\u00e7et<\/p>\n<p>Optikusatrophie als Folge einiger genetisch-famili\u00e4rer Erkrankungen wie der Leber-Krankheit<\/p>\n<p>Sch\u00e4digung des Sehnervs durch Augendruck, d. h. Glaukom<\/p>\n<p>Neben dem Auge k\u00f6nnen durch neurologische Erkrankungen Sch\u00e4digungen des Sehnervs und der Sehbahnen auftreten:<\/p>\n<p>Papillen\u00f6dem und damit verbundene Optikusatrophie als Folge eines erh\u00f6hten intrakraniellen Drucks (ICP)<\/p>\n<p>Druck auf das Chiasma opticum durch Hypophysenadenom oder Tumore<\/p>\n<p>Probleme mit Okzipitallappen und visuellem Kortex<\/p>\n<p>Migr\u00e4ne<\/p>\n<p>Blasenbildung in Hirngef\u00e4\u00dfen (Aneurysmen)<\/p>\n<p>Hirntumore<\/p>\n<p>Infektionen wie Meningitis-Enzephalitis<\/p>\n<p>Je nach Ort der Sch\u00e4digung des Sehnervs und der Sehbahnen kommt es zu verschiedenen Arten von Gesichtsfeldausf\u00e4llen.<\/p>\n<p>Bei Erkrankungen des Sehnervs sieht der Patient die Objekte verschwommen, hauchd\u00fcnn und blass; nimmt Gesichtsfeldverluste wahr.<\/p>\n<p>Der Lichtreflex ist auf der betroffenen Seite geschw\u00e4cht und Kontrastempfindlichkeit, Farbsehen und Gesichtsfeld sind beeintr\u00e4chtigt.<\/p>\n<p>Behandlung: Abh\u00e4ngig von der zugrunde liegenden Ursache erfolgt sie durch das entsprechende Fachgebiet der Medizin.<\/p>\n<p>Bei einer Optikusneuritis aufgrund von Multipler Sklerose wird die Myelinscheide besch\u00e4digt, die die Nervenleitung unterst\u00fctzt.<\/p>\n<p>Bei der isch\u00e4mischen Optikusneuropathie wird die Behandlungsmodalit\u00e4t bestimmt, nachdem die arteriitische\/nicht-arteriitische Unterscheidung durch eine hohe Sedimentationsrate gekennzeichnet ist. Bei arteriitischer Art ist zum Schutz des anderen Auges hochdosiertes und dauerhaftes Kortison erforderlich, bei nicht arteriitischer (Zucker-Blutdruckkontrolle) werden je nach Ursache Blutverd\u00fcnner zusammen mit Kortison verabreicht. Magnovision und Unterst\u00fctzung durch Wachstumsfaktoren k\u00f6nnen erforderlich sein, um die Durchblutung des Sehnervs zu erh\u00f6hen.<\/p>\n<p>Bei traumabedingten Sehnervenerkrankungen werden Magnovision und Wachstumsfaktorbehandlungen mit Kortison dringend eingesetzt.<\/p>\n<p>Die Ursache einer Erkrankung des Sehnervs kann mit anderen Untersuchungen, insbesondere MRT, verstanden werden.<\/p>\n<p>Optikusatrophie (Schw\u00e4chung, Austrocknung des Nervs) kann als Folge verschiedener Erkrankungen des Sehnervs auftreten. In diesem Fall k\u00f6nnen durch Stimulation der geschw\u00e4chten Sehnerven mit Magnovision\/Okuvision neue Sehbahnen aktiviert werden.<\/p>\n<p>Wenn die Augen und Sehbahnen vollst\u00e4ndig gesch\u00e4digt sind, scheint in naher Zukunft jede Blindheit geheilt zu werden, indem stimulierende Chips, also kortikale Prothesen, am Sehzentrum im Gehirn angebracht werden. Experimentelle Studien zu diesem Thema sind im Gange, und es gibt noch keine routinem\u00e4\u00dfige und breite Anwendung.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>PRP GROWTH FACTOR INJECTIONS MAGNOVISION THERAPY PHOTOBIOMODULATION THERAPY Die Sehfunktion beginnt, wenn Strahlen von Objekten auf der Netzhaut fokussiert werden. Lichtenergie wird in der Netzhaut in elektrische Energie umgewandelt. Diese elektrischen Impulse werden zum Sehzentrum im Gehirn \u00fcbertragen, indem sie durch den Sehnerv, das Sehchiasma und den Sehtrakt, die als Sehbahnen bezeichnet werden, geleitet werden. &hellip;<\/p>\n","protected":false},"author":1,"featured_media":4348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[105,55],"tags":[],"class_list":{"0":"post-5825","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-augenkrankheiten","8":"category-hastaliklar","9":"clearfix","10":"article"},"acf":[],"_links":{"self":[{"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/posts\/5825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/comments?post=5825"}],"version-history":[{"count":5,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/posts\/5825\/revisions"}],"predecessor-version":[{"id":6471,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/posts\/5825\/revisions\/6471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/media\/4348"}],"wp:attachment":[{"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/media?parent=5825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/categories?post=5825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bioretina.net\/de\/wp-json\/wp\/v2\/tags?post=5825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}